{"id":771,"date":"2023-01-12T07:41:51","date_gmt":"2023-01-12T07:41:51","guid":{"rendered":"https:\/\/biosiris.jmgmedia.com\/staging\/?post_type=product&#038;p=771"},"modified":"2026-08-20T16:27:52","modified_gmt":"2026-08-20T16:27:52","slug":"masque-peaux-jeunes","status":"publish","type":"product","link":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/","title":{"rendered":"Masque peaux jeunes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"771\" class=\"elementor elementor-771\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7038d13 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7038d13\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c36cbf\" data-id=\"2c36cbf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-810e0a2 elementor-widget elementor-widget-image\" data-id=\"810e0a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"205\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/a-1024x205.png\" class=\"attachment-large size-large wp-image-4537\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/a-1024x205.png 1024w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/a-300x60.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/a-768x154.png 768w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/a-1536x307.png 1536w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/a-2048x410.png 2048w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/a-600x120.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11dc023\" data-id=\"11dc023\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-606da72 elementor-widget elementor-widget-image\" data-id=\"606da72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"205\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/Sans-parfum-1024x205.png\" class=\"attachment-large size-large wp-image-4536\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/Sans-parfum-1024x205.png 1024w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/Sans-parfum-300x60.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/Sans-parfum-768x154.png 768w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/Sans-parfum-1536x307.png 1536w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/Sans-parfum-2048x410.png 2048w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/Sans-parfum-600x120.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce0a0f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce0a0f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0dea40c\" data-id=\"0dea40c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0644926 elementor-widget elementor-widget-text-editor\" data-id=\"0644926\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez notre masque peaux jeunes\u00a0sp\u00e9cialement formul\u00e9e pour <strong>r\u00e9pondre aux besoins des peaux jeunes, normales \u00e0 grasses, et \u00e0 probl\u00e8mes<\/strong>. Cette formule unique utilise des ingr\u00e9dients naturels soigneusement s\u00e9lectionn\u00e9s pour purifier, hydrater et r\u00e9parer en profondeur, r\u00e9v\u00e9lant une peau \u00e9clatante et parfaitement \u00e9quilibr\u00e9e.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbf34ed elementor-widget elementor-widget-heading\" data-id=\"cbf34ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FORMULE 100% NATURELLE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-886b8b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"886b8b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0a5a02\" data-id=\"b0a5a02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-328b05d elementor-widget elementor-widget-heading\" data-id=\"328b05d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Son secret ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cec45bf elementor-widget elementor-widget-image\" data-id=\"cec45bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"219\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/masque-jeune-1024x219.png\" class=\"attachment-large size-large wp-image-4906\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/masque-jeune-1024x219.png 1024w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/masque-jeune-300x64.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/masque-jeune-768x165.png 768w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/masque-jeune-1536x329.png 1536w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/masque-jeune-2048x439.png 2048w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/masque-jeune-600x129.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ce0e3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ce0e3e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1aa1565\" data-id=\"1aa1565\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8f6cb1 elementor-widget elementor-widget-text-editor\" data-id=\"e8f6cb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ne dess\u00e8che pas la peau gr\u00e2ce \u00e0 sa formule enrichie en huiles, cette \u00e9mulsion ne s\u00e8che pas \u00e0 la surface de la peau pendant le temps d&rsquo;application, contrairement aux autres produits du march\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90a1dd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90a1dd1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-463a1da\" data-id=\"463a1da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-578b781 elementor-widget elementor-widget-image\" data-id=\"578b781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/argile-verte.png\" class=\"attachment-large size-large wp-image-3445\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/argile-verte.png 1000w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/argile-verte-300x300.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/argile-verte-150x150.png 150w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/argile-verte-768x768.png 768w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/argile-verte-600x600.png 600w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/argile-verte-100x100.png 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3eb8c5d\" data-id=\"3eb8c5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6e4514 elementor-widget elementor-widget-spacer\" data-id=\"e6e4514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bfdc93 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7bfdc93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'argile verte et le th\u00e9 vert pour une purification intense<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9452266 elementor-widget elementor-widget-spacer\" data-id=\"9452266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef51fc9 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ef51fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>L&rsquo;argile verte naturelle<\/strong> pr\u00e9sente dans ce masque \u00e0 un fort pouvoir d&rsquo;absorption. Hautement s\u00e9lectionn\u00e9e, elle va permettre de purifier votre peau en profondeur sans la dess\u00e9cher, \u00e9liminant les impuret\u00e9s et l&rsquo;exc\u00e8s de s\u00e9bum. Elle est id\u00e9ale pour les peaux grasses.<\/li><li><strong>Le th\u00e9 vert et les huiles essentielles<\/strong> : Ce duo puissant aux propri\u00e9t\u00e9s assainissantes et antibact\u00e9riennes nettoie en profondeur et prot\u00e8ge votre peau, lui offrant une puret\u00e9 incomparable et une fra\u00eecheur durable.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29afcae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29afcae\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a90316\" data-id=\"5a90316\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e90209f elementor-widget elementor-widget-spacer\" data-id=\"e90209f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4176378 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4176378\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'Huile de Chanvre : Le Secret r\u00e9parateur et hydratant\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bb3011 elementor-widget elementor-widget-spacer\" data-id=\"4bb3011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48a9881 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"48a9881\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span style=\"font-size: 14px; color: #7a7a7a; font-weight: normal;\">L&rsquo;huile de chanvre pr\u00e9sente dans ce masque va permettre de <\/span><strong style=\"font-size: 14px; color: #7a7a7a;\">raffermir la peau<\/strong><span style=\"font-size: 14px; color: #7a7a7a;\"> <span style=\"font-weight: normal;\">tout en<\/span> r\u00e9tablissant son \u00e9clat. <span style=\"font-weight: normal;\">Elle <\/span>nourrit les cellules en profondeur <span style=\"font-weight: normal;\">et<\/span> hydrate la peau.<\/span><\/h4><h4><span style=\"font-size: 14px; color: #7a7a7a;\"><span style=\"font-weight: normal;\">Particuli\u00e8rement adapt\u00e9e au\u00a0<\/span>peaux sensibles,<span style=\"font-weight: normal;\"> elle<\/span> am\u00e9liore le teint en att\u00e9nuant les rougeurs.\u00a0<\/span><\/h4><h4><span style=\"font-size: 14px; color: #7a7a7a;\"><span style=\"font-weight: normal;\">En cas de peau s\u00e8che, elle apporte une<\/span> grande quantit\u00e9 de nutriment \u00e0 l&rsquo;\u00e9piderme et hydratation profonde. <span style=\"font-weight: normal;\">Pour l&rsquo;acn\u00e9 ses<\/span> propri\u00e9t\u00e9s anti-inflammatoires\u00a0<span style=\"font-weight: normal;\">sont b\u00e9n\u00e9fiques.<\/span><\/span><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d54612\" data-id=\"5d54612\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a94a941 elementor-widget elementor-widget-image\" data-id=\"a94a941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/huile-de-chanvre.png\" class=\"attachment-large size-large wp-image-3444\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/huile-de-chanvre.png 1000w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/huile-de-chanvre-300x300.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/huile-de-chanvre-150x150.png 150w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/huile-de-chanvre-768x768.png 768w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/huile-de-chanvre-600x600.png 600w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/huile-de-chanvre-100x100.png 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c999f2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c999f2a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b31c445\" data-id=\"b31c445\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23cca85 elementor-widget elementor-widget-image\" data-id=\"23cca85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/21.png\" class=\"attachment-large size-large wp-image-3446\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/21.png 1000w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/21-300x300.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/21-150x150.png 150w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/21-768x768.png 768w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/21-600x600.png 600w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/21-100x100.png 100w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e191a19\" data-id=\"e191a19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7c1039 elementor-widget elementor-widget-spacer\" data-id=\"a7c1039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efab775 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"efab775\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Huile de jojoba pour une hydratation compl\u00e8te<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-747c63c elementor-widget elementor-widget-spacer\" data-id=\"747c63c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5daa83 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d5daa83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cet ingr\u00e9dient miracle r\u00e9gule la production de s\u00e9bum et renforce le film hydrolipidique de votre peau, garantissant une hydratation optimale et un teint parfaitement \u00e9quilibr\u00e9 pour tous les types de peaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-801d702 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"801d702\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae93525\" data-id=\"ae93525\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e852575 elementor-widget elementor-widget-text-editor\" data-id=\"3e852575\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pot verre 50 ml<\/p><p><strong style=\"font-size: 14px;\">Certification Cosmos Organic. \u00a0<\/strong>Vegan<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b408221 elementor-widget elementor-widget-toggle\" data-id=\"b408221\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1881\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1881\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Sa composition et ses ingr\u00e9dients actifs<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1881\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1881\"><ul><li>Action purifiante de l\u2019<strong>argile verte<\/strong> et du <strong>th\u00e9 vert<\/strong> associ\u00e9e au complexe d\u2019huiles essentielles aux propri\u00e9t\u00e9s assainissantes et antibact\u00e9riennes.<\/li><li><strong>L\u2019huile de Jojoba<\/strong> r\u00e9gule le s\u00e9bum tout en renfor\u00e7ant le film hydrolipidique de la peau.<\/li><li><strong>L\u2019huile de chanvre<\/strong> poss\u00e8de des propri\u00e9t\u00e9s hydratantes et r\u00e9paratrices.<\/li><li><strong>Vitamine E naturelle<\/strong> antioxydante<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1882\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1882\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Conseils d'utilisation <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1882\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1882\"><p>Appliquer en couche \u00e9paisse sur le visage et le cou parfaitement nettoy\u00e9s (en \u00e9vitant le contour des yeux) et laisser poser 10 min. Rincer \u00e0 l&rsquo;eau claire.<\/p><p>L&rsquo;id\u00e9al est de le faire une fois par semaine.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1883\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1883\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ingr\u00e9dients (INCI)<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1883\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1883\"><p>Aqua, illite, simmondsia sinensis seed oil*, cannabis sativa seed oil*, cetyl alcohol, glycerin*, pentylene glycol, glyceryl stearate, cetearyl alcohol, stearic acid, sodium lauroyl glutamate, camellia sinensis leaf powder*, tocopherol, sorbitan caprylate, magnolia kobus bark extract, camelia sinensis leaf extract, chamomilla recutita flower extract, salix alba bark extract, thujopsis dolabrata branch extract, levulinic acid, cymbopogon martini oil*, malaleuca alternifolia leaf oil*, citrus sinensis peel oil expressed*, rosmarinus officinalis leaf oil*, citrus aurantium leaf oil*, geraniol, limonene, linalool, citral.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-656253a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"656253a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e4cefce\" data-id=\"e4cefce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12231b9 elementor-widget elementor-widget-heading\" data-id=\"12231b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Au coeur du produit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af38aab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af38aab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-027b93e\" data-id=\"027b93e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbd944c elementor-widget elementor-widget-image\" data-id=\"cbd944c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/fr-1.png\" class=\"attachment-large size-large wp-image-3318\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/fr-1.png 500w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/fr-1-300x300.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/fr-1-150x150.png 150w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/fr-1-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef99124 elementor-widget elementor-widget-text-editor\" data-id=\"ef99124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Artisans fran\u00e7ais<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-458dcac\" data-id=\"458dcac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfd37e2 elementor-widget elementor-widget-image\" data-id=\"bfd37e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/nat-2.png\" class=\"attachment-large size-large wp-image-3320\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/nat-2.png 500w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/nat-2-300x300.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/nat-2-150x150.png 150w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/nat-2-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f1361e elementor-widget elementor-widget-text-editor\" data-id=\"0f1361e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>FORMULE 100% NATURELLE<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-ffcb189\" data-id=\"ffcb189\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a0c9cd elementor-widget elementor-widget-image\" data-id=\"9a0c9cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/bio-1.png\" class=\"attachment-large size-large wp-image-3316\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/bio-1.png 500w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/bio-1-300x300.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/bio-1-150x150.png 150w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/bio-1-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-540b846 elementor-widget elementor-widget-text-editor\" data-id=\"540b846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>14,59% d\u2019ingr\u00e9dients BIO<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-c621881\" data-id=\"c621881\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9a664d elementor-widget elementor-widget-image\" data-id=\"f9a664d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/equi-1.png\" class=\"attachment-large size-large wp-image-3317\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/equi-1.png 500w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/equi-1-300x300.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/equi-1-150x150.png 150w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/equi-1-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af72e72 elementor-widget elementor-widget-text-editor\" data-id=\"af72e72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Contient des ingr\u00e9dients issus du commerce \u00e9quitable<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5d822c1\" data-id=\"5d822c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d09f17 elementor-widget elementor-widget-image\" data-id=\"4d09f17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/vegan.png\" class=\"attachment-large size-large wp-image-3338\" alt=\"\" srcset=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/vegan.png 500w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/vegan-300x300.png 300w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/vegan-150x150.png 150w, https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/vegan-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a54f236 elementor-widget elementor-widget-text-editor\" data-id=\"a54f236\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sans mati\u00e8re d\u2019origine animale<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ce masque a \u00e9t\u00e9 sp\u00e9cialement formul\u00e9 pour les peaux jeunes (normales \u00e0 grasses). Action purifiante de l&rsquo;argile verte et du th\u00e9 vert associ\u00e9e au complexe d&rsquo;huiles essentielles aux propri\u00e9t\u00e9s assainissantes et antibact\u00e9riennes. L&rsquo;huile de Jojoba r\u00e9gule le sebum tout en renfor\u00e7ant le film hydrolipidique de la peau. L&rsquo;huile de chanvre poss\u00e8de des propri\u00e9t\u00e9s hydratantes et r\u00e9paratrices.<\/p>\n","protected":false},"featured_media":3148,"comment_status":"open","ping_status":"closed","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0"},"product_brand":[],"product_cat":[58,37],"product_tag":[],"class_list":["post-771","product","type-product","status-publish","has-post-thumbnail","product_cat-peaux-jeunes","product_cat-soins-visage","entry","has-media","first","instock","shipping-taxable","purchasable","product-type-simple","has-rating","has-product-nav","col","span_1_of_4","owp-content-center","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Masque peaux jeunes - Biosiris Cosm\u00e9tiques<\/title>\n<meta name=\"description\" content=\"Masque Biosiris formul\u00e9 pour les peaux jeunes (normales \u00e0 grasses). Action purifiante de l&#039;argile verte associ\u00e9e aux huiles essentielles antibact\u00e9riennes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masque peaux jeunes - Biosiris Cosm\u00e9tiques\" \/>\n<meta property=\"og:description\" content=\"Masque Biosiris formul\u00e9 pour les peaux jeunes (normales \u00e0 grasses). Action purifiante de l&#039;argile verte associ\u00e9e aux huiles essentielles antibact\u00e9riennes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/\" \/>\n<meta property=\"og:site_name\" content=\"Biosiris Cosm\u00e9tiques\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/biosiris.cosmetiques\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-20T16:27:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/m-jeune-2-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/produit\\\/masque-peaux-jeunes\\\/\",\"url\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/produit\\\/masque-peaux-jeunes\\\/\",\"name\":\"Masque peaux jeunes - Biosiris Cosm\u00e9tiques\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/produit\\\/masque-peaux-jeunes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/produit\\\/masque-peaux-jeunes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/m-jeune-2-2-scaled.jpg\",\"datePublished\":\"2023-01-12T07:41:51+00:00\",\"dateModified\":\"2026-08-20T16:27:52+00:00\",\"description\":\"Masque Biosiris formul\u00e9 pour les peaux jeunes (normales \u00e0 grasses). Action purifiante de l'argile verte associ\u00e9e aux huiles essentielles antibact\u00e9riennes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/produit\\\/masque-peaux-jeunes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/produit\\\/masque-peaux-jeunes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/produit\\\/masque-peaux-jeunes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/m-jeune-2-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/m-jeune-2-2-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/produit\\\/masque-peaux-jeunes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/index.php\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Masque peaux jeunes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/#website\",\"url\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/\",\"name\":\"Biosiris Cosm\u00e9tiques\",\"description\":\"Biosiris Cosm\u00e9tiques - Soins naturels et biologiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/#organization\",\"name\":\"Biosiris Cosm\u00e9tiques\",\"url\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-biosiris-400.png\",\"contentUrl\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-biosiris-400.png\",\"width\":400,\"height\":175,\"caption\":\"Biosiris Cosm\u00e9tiques\"},\"image\":{\"@id\":\"https:\\\/\\\/biosiris-cosmetiques.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/biosiris.cosmetiques\",\"https:\\\/\\\/www.instagram.com\\\/biosiriscosmetiquesbio\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Masque peaux jeunes - Biosiris Cosm\u00e9tiques","description":"Masque Biosiris formul\u00e9 pour les peaux jeunes (normales \u00e0 grasses). Action purifiante de l'argile verte associ\u00e9e aux huiles essentielles antibact\u00e9riennes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/","og_locale":"fr_FR","og_type":"article","og_title":"Masque peaux jeunes - Biosiris Cosm\u00e9tiques","og_description":"Masque Biosiris formul\u00e9 pour les peaux jeunes (normales \u00e0 grasses). Action purifiante de l'argile verte associ\u00e9e aux huiles essentielles antibact\u00e9riennes.","og_url":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/","og_site_name":"Biosiris Cosm\u00e9tiques","article_publisher":"https:\/\/www.facebook.com\/biosiris.cosmetiques","article_modified_time":"2026-08-20T16:27:52+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/m-jeune-2-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/","url":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/","name":"Masque peaux jeunes - Biosiris Cosm\u00e9tiques","isPartOf":{"@id":"https:\/\/biosiris-cosmetiques.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/#primaryimage"},"image":{"@id":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/#primaryimage"},"thumbnailUrl":"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/m-jeune-2-2-scaled.jpg","datePublished":"2023-01-12T07:41:51+00:00","dateModified":"2026-08-20T16:27:52+00:00","description":"Masque Biosiris formul\u00e9 pour les peaux jeunes (normales \u00e0 grasses). Action purifiante de l'argile verte associ\u00e9e aux huiles essentielles antibact\u00e9riennes.","breadcrumb":{"@id":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/#primaryimage","url":"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/m-jeune-2-2-scaled.jpg","contentUrl":"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2023\/01\/m-jeune-2-2-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/biosiris-cosmetiques.com\/index.php\/produit\/masque-peaux-jeunes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/biosiris-cosmetiques.com\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/biosiris-cosmetiques.com\/index.php\/boutique\/"},{"@type":"ListItem","position":3,"name":"Masque peaux jeunes"}]},{"@type":"WebSite","@id":"https:\/\/biosiris-cosmetiques.com\/#website","url":"https:\/\/biosiris-cosmetiques.com\/","name":"Biosiris Cosm\u00e9tiques","description":"Biosiris Cosm\u00e9tiques - Soins naturels et biologiques","publisher":{"@id":"https:\/\/biosiris-cosmetiques.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biosiris-cosmetiques.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/biosiris-cosmetiques.com\/#organization","name":"Biosiris Cosm\u00e9tiques","url":"https:\/\/biosiris-cosmetiques.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/biosiris-cosmetiques.com\/#\/schema\/logo\/image\/","url":"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/logo-biosiris-400.png","contentUrl":"https:\/\/biosiris-cosmetiques.com\/wp-content\/uploads\/2022\/12\/logo-biosiris-400.png","width":400,"height":175,"caption":"Biosiris Cosm\u00e9tiques"},"image":{"@id":"https:\/\/biosiris-cosmetiques.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/biosiris.cosmetiques","https:\/\/www.instagram.com\/biosiriscosmetiquesbio\/"]}]}},"_links":{"self":[{"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/product\/771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/comments?post=771"}],"version-history":[{"count":23,"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/product\/771\/revisions"}],"predecessor-version":[{"id":4909,"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/product\/771\/revisions\/4909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/media\/3148"}],"wp:attachment":[{"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/media?parent=771"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=771"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=771"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/biosiris-cosmetiques.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}